{"id":77798,"date":"2020-12-23T13:07:44","date_gmt":"2020-12-23T12:07:44","guid":{"rendered":"https:\/\/www.bilbaodendak.eus\/comercios\/pena-athletic-casco-viejo\/"},"modified":"2020-12-23T13:07:44","modified_gmt":"2020-12-23T12:07:44","slug":"pena-athletic-casco-viejo","status":"publish","type":"comercios","link":"https:\/\/www.bilbaodendak.eus\/fr\/comercios\/pena-athletic-casco-viejo\/","title":{"rendered":"Pe\u00f1a Athletic Casco Viejo"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Ambiente rojiblanco<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\">Un restaurante con mucha historia<\/h4>\n\n\n\n<p>Si est\u00e1s de paseo por el Casco Viejo es inevitable entrar en el Caf\u00e9 Restaurante Pe\u00f1a Athletic.&nbsp; Te encontrar\u00e1s buenos pintxos, buen vino, ambiente athleticzale y gente encantadora a los dos lados de la barra. Puedes pasar a tomar algo o tambi\u00e9n puedes quedarte a comer o cenar: Tienen men\u00fa del d\u00eda, men\u00fa fin de semana y men\u00fa txulet\u00f3n. El personal es muy eficiente y eso es lo que hace que este lugar sea tan agradable y que siempre est\u00e9 lleno. Y si quieres que te lo lleven a casa, disponen tambi\u00e9n de servicio a domicilio. En el local se siente la cultura vasca y la historia del Athletic de Bilbao en estado puro, muestra de ello son todas y cada una de las piezas que adornan sus paredes.<\/p>\n\n\n\n<p>Reserva tu mesa con tiempo y\u2026 \u00a1A\u00fapa Athletic!<\/p>\n","protected":false},"featured_media":96106,"parent":0,"template":"","donde-aparcar":[],"etiquetas":[],"comprar":[],"comer":[606,609],"distritos":[849],"class_list":["post-77798","comercios","type-comercios","status-publish","has-post-thumbnail","hentry","comer-bares-cafeterias-fr","comer-bares-restaurantes-fr","distritos-casco-viejo-fr"],"_links":{"self":[{"href":"https:\/\/www.bilbaodendak.eus\/fr\/wp-json\/wp\/v2\/comercios\/77798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bilbaodendak.eus\/fr\/wp-json\/wp\/v2\/comercios"}],"about":[{"href":"https:\/\/www.bilbaodendak.eus\/fr\/wp-json\/wp\/v2\/types\/comercios"}],"version-history":[{"count":0,"href":"https:\/\/www.bilbaodendak.eus\/fr\/wp-json\/wp\/v2\/comercios\/77798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bilbaodendak.eus\/fr\/wp-json\/wp\/v2\/media\/96106"}],"wp:attachment":[{"href":"https:\/\/www.bilbaodendak.eus\/fr\/wp-json\/wp\/v2\/media?parent=77798"}],"wp:term":[{"taxonomy":"donde-aparcar","embeddable":true,"href":"https:\/\/www.bilbaodendak.eus\/fr\/wp-json\/wp\/v2\/donde-aparcar?post=77798"},{"taxonomy":"etiquetas","embeddable":true,"href":"https:\/\/www.bilbaodendak.eus\/fr\/wp-json\/wp\/v2\/etiquetas?post=77798"},{"taxonomy":"comprar","embeddable":true,"href":"https:\/\/www.bilbaodendak.eus\/fr\/wp-json\/wp\/v2\/comprar?post=77798"},{"taxonomy":"comer","embeddable":true,"href":"https:\/\/www.bilbaodendak.eus\/fr\/wp-json\/wp\/v2\/comer?post=77798"},{"taxonomy":"distritos","embeddable":true,"href":"https:\/\/www.bilbaodendak.eus\/fr\/wp-json\/wp\/v2\/distritos?post=77798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}